{"id":1632,"date":"2014-01-22T09:33:13","date_gmt":"2014-01-22T09:33:13","guid":{"rendered":""},"modified":"2014-01-22T09:33:13","modified_gmt":"2014-01-22T09:33:13","slug":"apostolado-del-mar-reforzar-solidaridad-entre-naciones","status":"publish","type":"post","link":"https:\/\/web.hilo.org.pe\/index.php\/2014\/01\/22\/apostolado-del-mar-reforzar-solidaridad-entre-naciones\/","title":{"rendered":"Apostolado del Mar: reforzar solidaridad entre naciones"},"content":{"rendered":"<div>\n<div>En su intervenci&oacute;n el purpurado pidi&oacute; tambi&eacute;n a los capellanes y a cuantos se ocupan de la asistencia de los marinos que estuvieran lo m&aacute;s posible al lado de aquellos que viven el drama de los secuestros en el mar y que mostrasen a sus familiares &ldquo;el rostro amoroso de la Iglesia&rdquo; y record&oacute; que el beato Juan Pablo II hab&iacute;a solicitado la promoci&oacute;n de un esp&iacute;ritu ecum&eacute;nico en el mundo mar&iacute;timo para fomentar la cooperaci&oacute;n y la coordinaci&oacute;n rec&iacute;proca de los proyectos entre las conferencias episcopales y los ordinarios locales adecu&aacute;ndolas al escenario actual. Frente al fen&oacute;meno de la apertura de nuevas rutas comerciales y la fusi&oacute;n de empresas para obtener los m&aacute;ximos beneficios, el cardenal ha insistido en la necesidad de reforzar la solidaridad entre las naciones y en la divisi&oacute;n de recursos.<\/div>\n<div>&nbsp;<\/div>\n<div>El Pontificio Consejo para la Pastoral de los Emigrantes e Itinerantes, para dirigir mejor la actividad del Apostolado del Mar ha dividido el mundo en nueve regiones: Am&eacute;rica del Norte y Caribe, Am&eacute;rica Latina, &Aacute;frica Oc&eacute;ano Indico, &Aacute;frica Occidental, Europa, Asia del Sur, Asia Oriental y del Sur, Estados &Aacute;rabes del Golfo y Gibuti.<\/div>\n<div>&nbsp;<\/div>\n<div>En el encuentro intervendr&aacute;n, entre otros, el presidente de la compa&ntilde;&iacute;a Vships -l&iacute;der mundial en el &aacute;mbito de los servicios mar&iacute;timos que cubre el comercio, los cruceros, la energ&iacute;a y la defensa-, que trazar&aacute; el mapa de las tendencias y los problemas del sector en los pr&oacute;ximos a&ntilde;os.&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Monse&ntilde;or Giacomo Martino, consultor del dicasterio y John Green (Apostolado del Mar en Gran Breta&ntilde;a) hablar&aacute;n de la crisis econ&oacute;mica actual y de c&oacute;mo el networking y la compartici&oacute;n de experiencias pastorales puedan contribuir a afrontarla.&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>Monse&ntilde;or Martino abordar&aacute; tambi&eacute;n el tr&aacute;gico argumento de la esclavitud moderna que afecta a un n&uacute;mero creciente de pescadores oblig&aacute;ndoles al trabajo forzado en naves sin seguridad en las que se juegan la vida, de la trata de seres humanos y de la explotaci&oacute;n sexual.&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<div>La abogado Deirdre Fiztpatrick, directora del Seafarers Right International (SRI), que se ocupa de la defensa de los marinos hablar&aacute; de las numerosas violaciones de derechos a los que se ven sometidos. (Fuente VIS)<\/div>\n<\/div>\n<div>&nbsp;<\/div>\n<p><a href=\"http:\/\/web.hilo.org.pe\/wp-content\/uploads\/pescadores.jpg\" target=\"_blank\" rel=\"noopener\">Ver archivo adjunto<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>?No podemos ignorar la situaci?n penosa que atraviesan muchos pescadores y sus familias&#8230;Y tambi?n nos acordamos de los marinos que son todav?a rehenes de los piratas y de sus familias que los esperan?. Con estas palabras el cardenal Antonio Maria Vegli?, Presidente del Pontificio Consejo para la Pastoral de los Emigrantes e Itinerantes inaugur? en Roma el Encuentro Anual de los Coordinadores del Apostolado del Mar que culmina el 24 de enero. Los participantes asistir?n a la audiencia general del Papa, ma?ana, 22 de enero.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-1632","post","type-post","status-publish","format-standard","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/comments?post=1632"}],"version-history":[{"count":0,"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/posts\/1632\/revisions"}],"wp:attachment":[{"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/media?parent=1632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/categories?post=1632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.hilo.org.pe\/index.php\/wp-json\/wp\/v2\/tags?post=1632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}